{"id":2013,"date":"2021-04-22T19:53:29","date_gmt":"2021-04-22T17:53:29","guid":{"rendered":"https:\/\/www.altea-alquilerdebarcos.com\/barcos\/astondoa\/"},"modified":"2026-04-10T11:43:43","modified_gmt":"2026-04-10T09:43:43","slug":"astondoa","status":"publish","type":"product","link":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/","title":{"rendered":"Astondoa 464 with captain"},"content":{"rendered":"<p><strong>Characteristics <\/strong> ( skipper obligatory )<\/p>\n<ul>\n<li>Brand : Astondoa<\/li>\n<li>Engine : 2 x 480 CV<\/li>\n<li>Size : 14 meters<\/li>\n<li>Max people : 9 people<\/li>\n<li>Equipment : Awning, solarium, swimming ladder, table, music, shower, cabin, kitchen, bedrooms, bathrooms<\/li>\n<li>The price included : equipment , place, cleaning, insurance , skipper , Paddle , Kayak, fuel (rute in Altea \/Calp)<\/li>\n<li>deposit 1000\u20ac<\/li>\n<\/ul>\n<p><strong>Not included food and drinks <\/strong><\/p>\n<p><strong>Low season (October at may ) skipper included anf fuel ( navigation altea and calpe )<\/strong><\/p>\n<p>&#8211; 1050\u20ac Half day<\/p>\n<p>&#8211; 1300\u20ac day<\/p>\n<p><strong>Medium season ( July y September ) skipper included anf fuel ( navigation altea and calpe )<\/strong><\/p>\n<p>&#8211; 1250\u20ac Half day<\/p>\n<p>&#8211; 1450\u20ac day<\/p>\n<p><strong>High season ( august ) skipper included anf fuel ( navigation altea and calpe )<\/strong><\/p>\n<p>&#8211; 1300\u20ac Half day<\/p>\n<p>&#8211; 1500\u20ac day<\/p>\n<p>If you are looking for the remarkable balance between luxury, comfort and fun, enjoy a great experience on this magnificent Astondoa yacht. Its exterior design presents a large solarium in the bow to enjoy the sun, relax and the sea breeze caressing the skin. A lounge on the flybridge with spectacular views from the top of the ship and the large cockpit area at the stern, is a space where you can enjoy the wonderful moments of Mediterranean gastronomy. . Its interior layout offers a spacious saloon, kitchen, three spacious cabins and two bathrooms with shower, toilet and sink. It has an air conditioning and heating system in all rooms, as well as portholes that facilitate natural ventilation. Thanks to its two 480CV engines each, this yacht offers great acceleration and top speed. Its elegant and slim hull make it an extremely safe and comfortable boat at any speed and in all kinds of weather conditions.<\/p>\n<p>Boat rental altea with Evasion Nautica<\/p>\n","protected":false},"excerpt":{"rendered":"[elementor-template id=\"481\"]\n","protected":false},"featured_media":3050,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[51],"product_tag":[],"class_list":{"0":"post-2013","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rent","8":"first","9":"instock","10":"virtual","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Astondoa 464 with captain - Evasion Nautica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Astondoa 464 with captain - Evasion Nautica\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/\" \/>\n<meta property=\"og:site_name\" content=\"Evasion Nautica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/evasionnautica.es\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T09:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2021\/04\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"1135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"[elementor-template id=&quot;481&quot;]\" \/>\n<meta name=\"twitter:site\" content=\"@evasion_nautica\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/\",\"url\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/\",\"name\":\"Astondoa 464 with captain - Evasion Nautica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg\",\"datePublished\":\"2021-04-22T17:53:29+00:00\",\"dateModified\":\"2026-04-10T09:43:43+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg\",\"width\":1125,\"height\":1135},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/boats\\\/astondoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Products\",\"item\":\"http:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Astondoa 464 with captain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/\",\"name\":\"Evasion Nautica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#organization\",\"name\":\"Evasion Nautica\",\"url\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/favicone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/favicone.jpg\",\"width\":512,\"height\":512,\"caption\":\"Evasion Nautica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altea-alquilerdebarcos.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/evasionnautica.es\",\"https:\\\/\\\/x.com\\\/evasion_nautica\",\"https:\\\/\\\/www.tripadvisor.fr\\\/Attraction_Review-g666316-d10486937-Reviews-Evasion_Nautica-Altea_Costa_Blanca_Province_of_Alicante_Valencian_Country.html\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Astondoa 464 with captain - Evasion Nautica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/","og_locale":"en_US","og_type":"article","og_title":"Astondoa 464 with captain - Evasion Nautica","og_url":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/","og_site_name":"Evasion Nautica","article_publisher":"https:\/\/www.facebook.com\/evasionnautica.es","article_modified_time":"2026-04-10T09:43:43+00:00","og_image":[{"width":1125,"height":1135,"url":"http:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2021\/04\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"[elementor-template id=\"481\"]","twitter_site":"@evasion_nautica","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/","url":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/","name":"Astondoa 464 with captain - Evasion Nautica","isPartOf":{"@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/#primaryimage"},"image":{"@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/#primaryimage"},"thumbnailUrl":"http:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2021\/04\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg","datePublished":"2021-04-22T17:53:29+00:00","dateModified":"2026-04-10T09:43:43+00:00","breadcrumb":{"@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/#primaryimage","url":"http:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2021\/04\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg","contentUrl":"http:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2021\/04\/70F97400-5A78-4F01-8D13-693B0D74A1A7.jpeg","width":1125,"height":1135},{"@type":"BreadcrumbList","@id":"http:\/\/www.altea-alquilerdebarcos.com\/en\/boats\/astondoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Products","item":"http:\/\/www.altea-alquilerdebarcos.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Astondoa 464 with captain"}]},{"@type":"WebSite","@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#website","url":"https:\/\/www.altea-alquilerdebarcos.com\/en\/","name":"Evasion Nautica","description":"","publisher":{"@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altea-alquilerdebarcos.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#organization","name":"Evasion Nautica","url":"https:\/\/www.altea-alquilerdebarcos.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2023\/12\/favicone.jpg","contentUrl":"https:\/\/www.altea-alquilerdebarcos.com\/wp-content\/uploads\/2023\/12\/favicone.jpg","width":512,"height":512,"caption":"Evasion Nautica"},"image":{"@id":"https:\/\/www.altea-alquilerdebarcos.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/evasionnautica.es","https:\/\/x.com\/evasion_nautica","https:\/\/www.tripadvisor.fr\/Attraction_Review-g666316-d10486937-Reviews-Evasion_Nautica-Altea_Costa_Blanca_Province_of_Alicante_Valencian_Country.html"]}]}},"_links":{"self":[{"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/product\/2013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/media\/3050"}],"wp:attachment":[{"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/media?parent=2013"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/product_brand?post=2013"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/product_cat?post=2013"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.altea-alquilerdebarcos.com\/en\/wp-json\/wp\/v2\/product_tag?post=2013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}